{"id":46317,"date":"2022-06-01T12:18:42","date_gmt":"2022-06-01T11:18:42","guid":{"rendered":"http:\/\/eg-reeds.com\/?p=46317"},"modified":"2024-10-22T13:21:40","modified_gmt":"2024-10-22T11:21:40","slug":"siguenos-instagram-egreeds","status":"publish","type":"post","link":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/","title":{"rendered":"S\u00edguenos en Instagram @egreeds"},"content":{"rendered":"<h1><strong>S\u00edguenos en Instagram @egreeds<\/strong><\/h1>\n<p>S\u00edguenos en Instagram para estar al d\u00eda de todas las novedades. Nuestro usuario es <strong>@egreeds<\/strong> . Tambi\u00e9n puedes seguirnos en todas nuestras redes sociales solo tienes que hacer clic en los iconos de abajo.<\/p>\n<div class=\"social-icons follow-icons\" ><a href=\"https:\/\/open.spotify.com\/show\/3wMpFxTtC80Fk201Z8YsUR?go=1&sp_cid=ee93b54993f8e4696b1e4cdfb84922a2&utm_source=embed_player_v&utm_medium=desktop&nd=1&dlsi=938b58ac33b14ed3\" data-label=\"Spotify\" target=\"_blank\" class=\"icon button circle is-outline tooltip spotify tooltip\" title=\"Follow on Spotify\" aria-label=\"Follow on Spotify\" rel=\"noopener nofollow\"><i class=\"fa-brands fa-spotify\"><\/i><\/a><a href=\"https:\/\/www.facebook.com\/EGREEDS\/\" target=\"_blank\" data-label=\"Facebook\" class=\"icon button circle is-outline tooltip facebook\" title=\"S\u00edguenos en Facebook\" aria-label=\"S\u00edguenos en Facebook\" rel=\"noopener nofollow\"><i class=\"icon-facebook\" aria-hidden=\"true\"><\/i><\/a><a href=\"https:\/\/www.instagram.com\/egreeds\/?hl=es\" target=\"_blank\" data-label=\"Instagram\" class=\"icon button circle is-outline tooltip instagram\" title=\"S\u00edguenos en Instagram\" aria-label=\"S\u00edguenos en Instagram\" rel=\"noopener nofollow\"><i class=\"icon-instagram\" aria-hidden=\"true\"><\/i><\/a><a href=\"https:\/\/www.tiktok.com\/@egreeds?lang=es\" target=\"_blank\" data-label=\"TikTok\" class=\"icon button circle is-outline tooltip tiktok\" title=\"S\u00edguenos en TikTok\" aria-label=\"S\u00edguenos en TikTok\" rel=\"noopener nofollow\"><i class=\"icon-tiktok\" aria-hidden=\"true\"><\/i><\/a><a href=\"https:\/\/twitter.com\/egreeds\" data-label=\"X\" target=\"_blank\" class=\"icon button circle is-outline tooltip x\" title=\"Seguir en X\" aria-label=\"Seguir en X\" rel=\"noopener nofollow\"><i class=\"icon-x\" aria-hidden=\"true\"><\/i><\/a><a href=\"https:\/\/www.threads.net\/@egreeds\" data-label=\"Threads\" target=\"_blank\" class=\"icon button circle is-outline tooltip threads\" title=\"Follow on Threads\" aria-label=\"Follow on Threads\" rel=\"noopener nofollow\"><i class=\"icon-threads\" aria-hidden=\"true\"><\/i><\/a><a href=\"https:\/\/www.linkedin.com\/in\/egreeds\/\" data-label=\"LinkedIn\" target=\"_blank\" class=\"icon button circle is-outline tooltip linkedin\" title=\"S\u00edguenos en LinkedIn\" aria-label=\"S\u00edguenos en LinkedIn\" rel=\"noopener nofollow\"><i class=\"icon-linkedin\" aria-hidden=\"true\"><\/i><\/a><a href=\"https:\/\/www.youtube.com\/channel\/UCn9OSmO6boMxg0UOACGnT5Q\" data-label=\"YouTube\" target=\"_blank\" class=\"icon button circle is-outline tooltip youtube\" title=\"S\u00edguenos en Youtube\" aria-label=\"S\u00edguenos en Youtube\" rel=\"noopener nofollow\"><i class=\"icon-youtube\" aria-hidden=\"true\"><\/i><\/a><\/div>\n<p>Recuerda que nuestra tienda online de ca\u00f1as y palas de oboe y todo lo necesario para su fabricaci\u00f3n est\u00e1 siempre disponible para ti en nuestra web: <a href=\"https:\/\/eg-reeds.com\/es\/\" target=\"_blank\" rel=\"noopener\"><strong>www.eg-reeds.com<\/strong><\/a><\/p>\n<p>Te dejamos con nuestros \u00faltimos posts en Instagram.<\/p>\n\n  \n    <div class=\"row large-columns-3 medium-columns- small-columns-2 row-small\" >\n  <div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--video\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/reel\/DYNFiezGmMV\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg4-2.cdninstagram.com\/v\/t51.71878-15\/688358701_1696084444753199_6342589168327152891_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=100&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=jDYkuBNg6n4Q7kNvwE9JGyv&#038;_nc_oc=Adon15h1TCD4nh8JAoek1jSxoX1DcUCAIgMANC8872BFAlTcx9m6f1h1_GXZ2sOs-BT9imDzSdiOYGbuT2_lSY8Q&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg4-2.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQHbWKNa4kmBz5i-FV6ZsB8AUgYWlqtPoYgiJ-ovsmO_3V-vOHOEjjAPkcVJe3jd97tYEgwprT2W&#038;oh=00_Af7BrMvSLrq-vkE1Ef-ehGA5CTZfkRfORy5VLicr0x852g&#038;oe=6A0AC1FC\" alt=\"\ud83c\udfa7\ud83c\udf99\ufe0f Nuevo episodio de La Comunidad del Oboe con Jes\u00fas Pinillos.\n\nHoy tengo el gusto de charlar con Jes\u00fas Pinillos, actual solista de la Rotterdam Philharmonic Orchestra.\n\nDesde sus a\u00f1os de formaci\u00f3n hasta sus tocar en Berl\u00edn, Helsinki, Bamberg, Ginebra o Leipzig. Jes\u00fas comparte sus tips y su experiencia profesional desde dentro: audiciones, aprendizajes, momentos clave y la exigencia real de tocar al m\u00e1ximo nivel.\n\n\ud83d\udc49 Ya lo puedes ver aqu\u00ed:\n\ud83c\udf0d www.lacomunidaddeloboe.com\n\n\ud83d\udcac Dale like, suscr\u00edbete y comp\u00e1rtelo con otros obo\u00edstas, estudiantes y amantes de la m\u00fasica.\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #podcast #oboista #orquesta #oboist\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\ud83c\udfa7\ud83c\udf99\ufe0f Nuevo episodio de La Comunidad del Oboe con Jes\u00fas Pinillos.\n\nHoy tengo el gusto de charlar con Jes\u00fas Pinillos, actual solista de la Rotterdam Philharmonic Orchestra.\n\nDesde sus a\u00f1os de formaci\u00f3n hasta sus tocar en Berl\u00edn, Helsinki, Bamberg, Ginebra o Leipzig. Jes\u00fas comparte sus tips y su experiencia profesional desde dentro: audiciones, aprendizajes, momentos clave y la exigencia real de tocar al m\u00e1ximo nivel.\n\n\ud83d\udc49 Ya lo puedes ver aqu\u00ed:\n\ud83c\udf0d www.lacomunidaddeloboe.com\n\n\ud83d\udcac Dale like, suscr\u00edbete y comp\u00e1rtelo con otros obo\u00edstas, estudiantes y amantes de la m\u00fasica.\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #podcast #oboista #orquesta #oboist<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--image\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/p\/DYKggIADU-k\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg6-1.cdninstagram.com\/v\/t51.82787-15\/694949202_18579914860010353_9139777339915510002_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=103&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&#038;_nc_ohc=F2PSPrOYcMkQ7kNvwECZmTr&#038;_nc_oc=Adr500mf97lGOUpbfTJ3yqf0n7odTK6-sTp-nbY8EqbEGRVFnoVLLFefj6dh-F8OtqjitW-ERnODBZl9Wwx3_Vxu&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg6-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQHdl5aHta4GPDN3q8zLAepOiQ32ZYJlf8uiZsFdVmuQhEQ4-QkbtuOdaKHO_XClEueKv_lDiFG1&#038;oh=00_Af4khmFb9uDtAHvBExGySdEYxLsrqPU0Z-4ifR8_JylC_Q&#038;oe=6A0ABF20\" alt=\"Ma\u00f1ana lunes 11 a las 18h. nos visita Jes\u00fas Pinillos! \ud83d\udc4f\u263a\ufe0f\n\nSolista de la Rotterdam Philharmonic Orchestra y uno de los obo\u00edstas espa\u00f1oles con una trayectoria internacional impresionante.\n\nHa sido solista de oboe en la Deutsches Symphonieorchester Berlin y ha colaborado con orquestas como la Mahler Chamber Orchestra, hr-Sinfonieorchester, Konzerthausorchester Berlin, Deutsche Oper Berlin, Bamberger Symphoniker, Finnish Radio Symphony Orchestra, Budapest Festival Orchestra, Orchestre de la Suisse Romande, Gewandhausorchester y muchas m\u00e1s.\n\nNo te pierdas este fant\u00e1stico podcast de La Comunidad del Oboe!! \ud83d\udd25\n\u23e9 Con nuevo horario esta temporada a las 18:00!! \u23ea\n\nRecuerda que tienes todos los podcast en\nwww.lacomunidaddeloboe.com\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboist #orquesta #orchestra #podcast\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">Ma\u00f1ana lunes 11 a las 18h. nos visita Jes\u00fas Pinillos! \ud83d\udc4f\u263a\ufe0f\n\nSolista de la Rotterdam Philharmonic Orchestra y uno de los obo\u00edstas espa\u00f1oles con una trayectoria internacional impresionante.\n\nHa sido solista de oboe en la Deutsches Symphonieorchester Berlin y ha colaborado con orquestas como la Mahler Chamber Orchestra, hr-Sinfonieorchester, Konzerthausorchester Berlin, Deutsche Oper Berlin, Bamberger Symphoniker, Finnish Radio Symphony Orchestra, Budapest Festival Orchestra, Orchestre de la Suisse Romande, Gewandhausorchester y muchas m\u00e1s.\n\nNo te pierdas este fant\u00e1stico podcast de La Comunidad del Oboe!! \ud83d\udd25\n\u23e9 Con nuevo horario esta temporada a las 18:00!! \u23ea\n\nRecuerda que tienes todos los podcast en\nwww.lacomunidaddeloboe.com\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboist #orquesta #orchestra #podcast<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--video\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/reel\/DYFXGUCghKQ\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg4-3.cdninstagram.com\/v\/t51.71878-15\/673147017_932984019735689_3374139590492851664_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=111&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=mNYs_SmyXCgQ7kNvwEPGEyD&#038;_nc_oc=AdrTWpUvro5nO6cV-c00ZXdJ7cYVxsP1q7mOm9ldTuqwqxUrq76DEOSgGf0FOwAEzVUI5uFc-5gdjYiUgPs9p_JV&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg4-3.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQG8K7DvhO8GzHxqNmD967BRKs6AoSM8h8Oa-1UvM5lxCc5-kab-Whukunq7XUosNTCY5BG6fvHb&#038;oh=00_Af5UgrXpGLdJ9xuNUOtCP5idqNdt_7N2yPN7RlAn60W0MA&#038;oe=6A0AA7A2\" alt=\"\u00bfQuieres saber c\u00f3mo empezar a raspar una ca\u00f1a con c\u00fater?\n\nEn el v\u00eddeo te ense\u00f1o c\u00f3mo empiezo quitando el esmalte.\n\n\ud83d\udc49 esto ayuda a que la navaja no se desafile tan r\u00e1pido.\n\nEl esmalte exterior de la ca\u00f1a es m\u00e1s duro, y si lo trabajas directamente con la navaja, el filo sufre m\u00e1s.\n\n\u00bfY t\u00fa ya has probado a empezar las ca\u00f1as con c\u00fater?\n\nTe leo en comentarios \ud83d\udc47\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n-\n\nDo you want to know how to start scraping an oboe reed with a cutter? \n\nIn this video, I show you how I start by removing the bark.\n\n\ud83d\udc49 it helps prevent your knife from getting dull too quickly.\n\nThe outer bark of the cane is harder, and if you work on it directly with your knife, the edge will wear down faster.\n\nHave you already tried starting your reeds with a cutter?\n\nLet me know in the comments \ud83d\udc47\n\nBest regards and good reeds! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboereeds #reedmaking #oboist #oboista\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\u00bfQuieres saber c\u00f3mo empezar a raspar una ca\u00f1a con c\u00fater?\n\nEn el v\u00eddeo te ense\u00f1o c\u00f3mo empiezo quitando el esmalte.\n\n\ud83d\udc49 esto ayuda a que la navaja no se desafile tan r\u00e1pido.\n\nEl esmalte exterior de la ca\u00f1a es m\u00e1s duro, y si lo trabajas directamente con la navaja, el filo sufre m\u00e1s.\n\n\u00bfY t\u00fa ya has probado a empezar las ca\u00f1as con c\u00fater?\n\nTe leo en comentarios \ud83d\udc47\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n-\n\nDo you want to know how to start scraping an oboe reed with a cutter? \n\nIn this video, I show you how I start by removing the bark.\n\n\ud83d\udc49 it helps prevent your knife from getting dull too quickly.\n\nThe outer bark of the cane is harder, and if you work on it directly with your knife, the edge will wear down faster.\n\nHave you already tried starting your reeds with a cutter?\n\nLet me know in the comments \ud83d\udc47\n\nBest regards and good reeds! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboereeds #reedmaking #oboist #oboista<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--carousel_album\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/p\/DX9ortJltmY\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg6-1.cdninstagram.com\/v\/t51.82787-15\/685062948_18578616766010353_402309710457926813_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=103&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0FST1VTRUxfSVRFTS5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&#038;_nc_ohc=f4jW6-diMlkQ7kNvwEFlDY-&#038;_nc_oc=AdqeycoIwcjItCgyQomNInQortl4RO3lrICrasJB_ATXsRVMwFcRBAQBqk5qj1YxcARIS96hB4MfJBDahrr75kis&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg6-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQEjuWKjNgcSoheyp9pU4Wtyn2sanHDAfOZltY1KXz1WDBFhXRUaAZ97R0jG4tO-lwNw4rFnDSPo&#038;oh=00_Af4_DU1sZyelXcuYEWtX_QMRuSfKk34S4hqiNNs6mn7d8g&#038;oe=6A0AAC5B\" alt=\"\ud83d\udc40 Hemos preparado un tutorial completo en el blog sobre navajas.\n\nAh\u00ed explicamos los tipos de navajas para hacer ca\u00f1as de oboe, para qu\u00e9 sirve cada una y qu\u00e9 deber\u00edas tener en cuenta seg\u00fan tu nivel, tu t\u00e9cnica y tu forma de raspar.\n\n\ud83d\udc49\ud83d\udcd6 Lee el art\u00edculo completo en nuestro blog. \n\n\u00bfT\u00fa ya tienes una favorita?\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n--\n\n\ud83d\udc40 We\u2019ve prepared a complete tutorial on the blog about knives. \n\nIn it, we explain the different types of knives for making oboe reeds, what each one is used for, and what you should consider depending on your level, your technique and the way you scrape.\n\n\ud83d\udc49\ud83d\udcd6 Read the full article in our blog. \n\nDo you already have a favourite one?\n\nBest regards and good reeds! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboereeds #oboist #reedmaking #tutorial\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\ud83d\udc40 Hemos preparado un tutorial completo en el blog sobre navajas.\n\nAh\u00ed explicamos los tipos de navajas para hacer ca\u00f1as de oboe, para qu\u00e9 sirve cada una y qu\u00e9 deber\u00edas tener en cuenta seg\u00fan tu nivel, tu t\u00e9cnica y tu forma de raspar.\n\n\ud83d\udc49\ud83d\udcd6 Lee el art\u00edculo completo en nuestro blog. \n\n\u00bfT\u00fa ya tienes una favorita?\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n--\n\n\ud83d\udc40 We\u2019ve prepared a complete tutorial on the blog about knives. \n\nIn it, we explain the different types of knives for making oboe reeds, what each one is used for, and what you should consider depending on your level, your technique and the way you scrape.\n\n\ud83d\udc49\ud83d\udcd6 Read the full article in our blog. \n\nDo you already have a favourite one?\n\nBest regards and good reeds! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboereeds #oboist #reedmaking #tutorial<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--video\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/reel\/DXuL1m3jh3s\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg4-1.cdninstagram.com\/v\/t51.71878-15\/684697388_2712015285849017_5743772236704899703_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=108&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=aEm-2M1VKQwQ7kNvwFYjRPV&#038;_nc_oc=AdrKLlxCZuVh4wNqLOFWrprikgM3XHzNfwz9hcLGxTtZl3DLmx0WTtGHI6MkBrjvPdigFVlB8NA4WjcS8Id_4K95&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg4-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQE8kCmr_wnWoZbd1yCvRFSP4jc_Q0vKBEdnIVzh-M2VNuQqpCrOUXSkDxzYXwCA-eNcPloTFEFx&#038;oh=00_Af4sR00To9nXmhGS8Ts4U6BaEgBoVCMJLmiyvBk71YDFQw&#038;oe=6A0A91E9\" alt=\"\ud83c\udfb6 \u00bfCu\u00e1l es tu navaja perfecta para hacer ca\u00f1as?\n\nNo todas las navajas sirven para lo mismo.\n\nHay quien busca m\u00e1xima precisi\u00f3n para raspar la punta.\nHay quien necesita una hoja c\u00f3moda para empezar.\nY hay quien prefiere, como yo, empezar con un c\u00fater para quitar el esmalte.\n\nEn EG-REEDS tienes diferentes modelos para elegir seg\u00fan tu nivel, tu t\u00e9cnica y lo que buscas al raspar.\n\n\ud83d\udc49 Mira el v\u00eddeo, compara y cu\u00e9ntanos en comentarios: \u00bfCu\u00e1l ser\u00eda tu navaja perfecta? \n\nY si tienes dudas, escr\u00edbenos. Te ayudamos a elegir la mejor para ti.\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n--\n\n\ud83c\udfb6 What\u2019s your perfect knife for reed making?\n\nNot all knives are made for the same job.\n\nSome players look for maximum precision when scraping the tip.\nSome need a comfortable blade to get started.\nAnd some, like me, prefer to begin with a cutter to remove the bark.\n\nAt EG-REEDS, you\u2019ll find different models depending on your level, your technique and the feeling you want when scraping.\n\n\ud83d\udc49 Watch the video, compare them and tell us in the comments: Which one would be your perfect knife? \n\nAnd if you have any doubts, send us a message. We\u2019ll help you choose the right one for you.\n\nBest regards and good reeds! \ud83d\udc4b\ud83c\udfb6\n\n\ud83d\udcbb www.eg-reeds.com\n\n#oboe #reedmaking #oboist #oboista #oboereeds\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\ud83c\udfb6 \u00bfCu\u00e1l es tu navaja perfecta para hacer ca\u00f1as?\n\nNo todas las navajas sirven para lo mismo.\n\nHay quien busca m\u00e1xima precisi\u00f3n para raspar la punta.\nHay quien necesita una hoja c\u00f3moda para empezar.\nY hay quien prefiere, como yo, empezar con un c\u00fater para quitar el esmalte.\n\nEn EG-REEDS tienes diferentes modelos para elegir seg\u00fan tu nivel, tu t\u00e9cnica y lo que buscas al raspar.\n\n\ud83d\udc49 Mira el v\u00eddeo, compara y cu\u00e9ntanos en comentarios: \u00bfCu\u00e1l ser\u00eda tu navaja perfecta? \n\nY si tienes dudas, escr\u00edbenos. Te ayudamos a elegir la mejor para ti.\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n--\n\n\ud83c\udfb6 What\u2019s your perfect knife for reed making?\n\nNot all knives are made for the same job.\n\nSome players look for maximum precision when scraping the tip.\nSome need a comfortable blade to get started.\nAnd some, like me, prefer to begin with a cutter to remove the bark.\n\nAt EG-REEDS, you\u2019ll find different models depending on your level, your technique and the feeling you want when scraping.\n\n\ud83d\udc49 Watch the video, compare them and tell us in the comments: Which one would be your perfect knife? \n\nAnd if you have any doubts, send us a message. We\u2019ll help you choose the right one for you.\n\nBest regards and good reeds! \ud83d\udc4b\ud83c\udfb6\n\n\ud83d\udcbb www.eg-reeds.com\n\n#oboe #reedmaking #oboist #oboista #oboereeds<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--video\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/reel\/DXpB3hWoGC3\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg4-2.cdninstagram.com\/v\/t51.82787-15\/681287202_18576403513010353_4262701176515120748_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=107&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=7dNUD-KdFmcQ7kNvwGqZWyO&#038;_nc_oc=AdrOsh6EZuR6PQLa7uPIylqW9vu6xBw6UhTFN4B-TrMd5aBVX5zdIP3i2nf-ypfznHcrMiulJUV8PYl8j2ogVoA1&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg4-2.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQGKgU2TBXk4TjkqDzsB3WK2ANtOnj01Gn_tCra_LDuqqIiyc4LmNBvV80G-Qf7QsT_6lkyd-PzJ&#038;oh=00_Af5_vkCxoyEeMLARfnVyL_oNE9tznrFSwwZ4KVbE_T_d1A&#038;oe=6A0A9474\" alt=\"\ud83c\udfa7 Nuevo episodio de La Comunidad del Oboe con Guillermo Dalia.\n\nYa tienes disponible el podcast con Guillermo Dalia, Doctor en Psicolog\u00eda, especialista en Psicolog\u00eda Cl\u00ednica y referente mundial en psicolog\u00eda aplicada a m\u00fasicos.\n\nDesde 1993, su trabajo se centra en mejorar la calidad de vida de los m\u00fasicos a trav\u00e9s de la formaci\u00f3n, la psicoterapia, la investigaci\u00f3n y la publicaci\u00f3n de libros sobre psicolog\u00eda de la m\u00fasica.\n\nHablamos sobre miedo esc\u00e9nico, ansiedad, presi\u00f3n en los conservatorios, salud mental, relaci\u00f3n profesor alumno, burnout y c\u00f3mo construir una vida musical m\u00e1s sana, consciente y equilibrada.\n\nUna conversaci\u00f3n muy necesaria para estudiantes, profesores, familias y profesionales de la m\u00fasica.\n\n\ud83d\udc49 Ya lo puedes ver aqu\u00ed:\n\ud83c\udf0d www.lacomunidaddeloboe.com\n\n\ud83d\udcac Dale like, suscr\u00edbete y comp\u00e1rtelo con quien t\u00fa quieras.\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #podcast #psicologiamusical #miedoescenico #musicos\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\ud83c\udfa7 Nuevo episodio de La Comunidad del Oboe con Guillermo Dalia.\n\nYa tienes disponible el podcast con Guillermo Dalia, Doctor en Psicolog\u00eda, especialista en Psicolog\u00eda Cl\u00ednica y referente mundial en psicolog\u00eda aplicada a m\u00fasicos.\n\nDesde 1993, su trabajo se centra en mejorar la calidad de vida de los m\u00fasicos a trav\u00e9s de la formaci\u00f3n, la psicoterapia, la investigaci\u00f3n y la publicaci\u00f3n de libros sobre psicolog\u00eda de la m\u00fasica.\n\nHablamos sobre miedo esc\u00e9nico, ansiedad, presi\u00f3n en los conservatorios, salud mental, relaci\u00f3n profesor alumno, burnout y c\u00f3mo construir una vida musical m\u00e1s sana, consciente y equilibrada.\n\nUna conversaci\u00f3n muy necesaria para estudiantes, profesores, familias y profesionales de la m\u00fasica.\n\n\ud83d\udc49 Ya lo puedes ver aqu\u00ed:\n\ud83c\udf0d www.lacomunidaddeloboe.com\n\n\ud83d\udcac Dale like, suscr\u00edbete y comp\u00e1rtelo con quien t\u00fa quieras.\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #podcast #psicologiamusical #miedoescenico #musicos<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--image\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/p\/DXmdPjRDBA9\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg4-2.cdninstagram.com\/v\/t51.82787-15\/681280583_18576169831010353_4515198419724042544_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=107&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&#038;_nc_ohc=rkGw7Py3hC8Q7kNvwFxrqV8&#038;_nc_oc=AdqAT17_02xlVGfL6uI2QDbWMDVHhItVuX0dzGE-PVgvKnsaZu1UFXR2MUX6bCPAgRVl0pY30OKwKXdYgy6WhspG&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg4-2.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQGmjPIuSe1dZ5AnEx7KfXkRB1-Gns5v4cAbdMwy3PODGmC15mWuRF1KvWg9kyk4aqhl1mEDmoV_&#038;oh=00_Af7-pOpOq0u03iCPBVIVXyVdLI6CO6EVfWNQgs1MLvJ95Q&#038;oe=6A0A920E\" alt=\"\u2728Este lunes 27 a las 18:00h tienes nuevo podcast en La Comunidad del Oboe \ud83c\udf99\ufe0f\u2728\n\nNos acompa\u00f1ar\u00e1 Guillermo Dalia Cirujeda, referente en psicolog\u00eda para m\u00fasicos, para hablar de ansiedad esc\u00e9nica, rendimiento y bienestar en la m\u00fasica.\n\nUna conversaci\u00f3n muy necesaria para estudiantes, profesores y m\u00fasicos profesionales que quieren entender mejor qu\u00e9 ocurre antes de subir al escenario y c\u00f3mo vivir la m\u00fasica de una forma m\u00e1s sana.\n\nEl lunes en: www.lacomunidaddeloboe.com No te lo pierdas!!\n\n\u00a1Saludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboist #podcast #musicos #psicologia\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\u2728Este lunes 27 a las 18:00h tienes nuevo podcast en La Comunidad del Oboe \ud83c\udf99\ufe0f\u2728\n\nNos acompa\u00f1ar\u00e1 Guillermo Dalia Cirujeda, referente en psicolog\u00eda para m\u00fasicos, para hablar de ansiedad esc\u00e9nica, rendimiento y bienestar en la m\u00fasica.\n\nUna conversaci\u00f3n muy necesaria para estudiantes, profesores y m\u00fasicos profesionales que quieren entender mejor qu\u00e9 ocurre antes de subir al escenario y c\u00f3mo vivir la m\u00fasica de una forma m\u00e1s sana.\n\nEl lunes en: www.lacomunidaddeloboe.com No te lo pierdas!!\n\n\u00a1Saludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboist #podcast #musicos #psicologia<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--carousel_album\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/p\/DXewvp7DCcT\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/eg-reeds.com\/wp-content\/themes\/flatsome\/assets\/img\/missing.jpg\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\ud83d\udcda\ud83e\udd29 Sorpresa!! \ud83d\ude0a\ud83e\udd29\n\nEl lunes 27 tenemos el honor de tener en La Comunidad del Oboe a un referente de la psicolog\u00eda para m\u00fasicos: Guillermo Dalia @guillermodaliacirujeda\n\nPara ir abriendo boca, y aprovechando el d\u00eda del libro, te dejamos un TOP 5 de sus libros que todo m\u00fasico deber\u00eda conocer. Feliz d\u00eda del libro a tod@s! \n\n\ud83e\udde0 C\u00f3mo superar la ansiedad esc\u00e9nica en m\u00fasicos\n\ud83d\ude0a C\u00f3mo ser feliz si eres musico o tienes uno cerca\n\ud83c\udfaf El m\u00fasico interior\n\u26a0\ufe0f El m\u00fasico adicto (la musicorexia)\n\ud83d\udcaa Fuerza mental del m\u00fasico\n\nY atent@\u2026\n\ud83c\udfa7 Este lunes no te pierdas el podcast!! Es oro puro!! En www.lacomunidaddeloboe.com\n\nSaludos y buenas ca\u00f1as!!\ud83d\udc4b\ud83c\udfb6\n\n#oboe #musicos #psicologia #libros #felizd\u00edadellibro<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--carousel_album\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/p\/DXcLJNBDde4\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg6-1.cdninstagram.com\/v\/t51.82787-15\/671744207_18575077600010353_1782281632478306357_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=103&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0FST1VTRUxfSVRFTS5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&#038;_nc_ohc=ph7Vu0oashQQ7kNvwGhUK5k&#038;_nc_oc=AdrxtgImmeDmETAPtG7ashAIPLjWAP3hGkWWmPB6Awm-QGkv1XjYvzL_ts3l6QRfwD0Bcg7g8bjgahsJPqsS0X_m&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg6-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQHvo-p47_PcKuczZLucx_9F_Tn0wZyYvKf3lfKs_GRmKhBpv4riJ-BLh_bjJsE6uGRGzHXH-XkM&#038;oh=00_Af6Z2NWvPu0aqsLPSWgIImwsXMaTdU6En0NGkkCa0r-V_A&#038;oe=6A0AA76E\" alt=\"\ud83c\udfc6 The Muri Competition 2026 has crowned its winners in the oboe category.\n\n Results:\n\ud83e\udd47 Fedor Osver\n\ud83e\udd48 Varvara Petrova\n\ud83e\udd49 Pedro Moreira\n\n\ud83d\udcf8 Photos: Muri Competition 2026 official media.\n\nAt EG-REEDS, we congratulate all the prize winners and participants for the outstanding artistic level of this edition.\n\n\ud83d\udc49 Read the full article on the EG-REEDS blog: https:\/\/eg-reeds.com\/oboe-results-the-muri-competition-2026\/\n\nBest regards and good reeds! \ud83d\udc4b\ud83c\udfb6--\n--\n\n\ud83c\udfc6 El Muri Competition 2026 ya tiene ganadores en la categor\u00eda de oboe.\n\nResultado:\n\ud83e\udd47 Fedor Osver\n\ud83e\udd48 Varvara Petrova\n\ud83e\udd49 Pedro Moreira\n\n\ud83d\udcf8 Fotos: Muri Competition 2026 web oficial.\n\nDesde EG-REEDS felicitamos a los premiados y a todos los participantes por el alt\u00edsimo nivel art\u00edstico de esta edici\u00f3n.\n\n\ud83d\udc49 Lee el art\u00edculo completo en el blog de EG-REEDS: https:\/\/eg-reeds.com\/es\/resultados-oboe-the-muri-competition-2026\/\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboist #music #muri #competition\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\ud83c\udfc6 The Muri Competition 2026 has crowned its winners in the oboe category.\n\n Results:\n\ud83e\udd47 Fedor Osver\n\ud83e\udd48 Varvara Petrova\n\ud83e\udd49 Pedro Moreira\n\n\ud83d\udcf8 Photos: Muri Competition 2026 official media.\n\nAt EG-REEDS, we congratulate all the prize winners and participants for the outstanding artistic level of this edition.\n\n\ud83d\udc49 Read the full article on the EG-REEDS blog: https:\/\/eg-reeds.com\/oboe-results-the-muri-competition-2026\/\n\nBest regards and good reeds! \ud83d\udc4b\ud83c\udfb6--\n--\n\n\ud83c\udfc6 El Muri Competition 2026 ya tiene ganadores en la categor\u00eda de oboe.\n\nResultado:\n\ud83e\udd47 Fedor Osver\n\ud83e\udd48 Varvara Petrova\n\ud83e\udd49 Pedro Moreira\n\n\ud83d\udcf8 Fotos: Muri Competition 2026 web oficial.\n\nDesde EG-REEDS felicitamos a los premiados y a todos los participantes por el alt\u00edsimo nivel art\u00edstico de esta edici\u00f3n.\n\n\ud83d\udc49 Lee el art\u00edculo completo en el blog de EG-REEDS: https:\/\/eg-reeds.com\/es\/resultados-oboe-the-muri-competition-2026\/\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboist #music #muri #competition<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--carousel_album\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/p\/DXXAmiRDNOz\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg4-1.cdninstagram.com\/v\/t51.82787-15\/674431738_18574623910010353_2448919291063317493_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=104&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0FST1VTRUxfSVRFTS5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&#038;_nc_ohc=6CNToVd0iHUQ7kNvwHdKBZ0&#038;_nc_oc=AdrML5_9LKwVgw0nzTXXQvi2aU7yw18wvxaqksDn75uMF2LMkIxDed1Sg6-XSVzK0df1jEhCs-OfokoHWpyfcOCe&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg4-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQGdl5Gd4n0m02mmhZWeFpXIP8dmMCgrUXksR6FqWGjpJ1yx0stsdEshKxOznJ1_jGYegbdUpbA2&#038;oh=00_Af4m63YfbYySl_C3cWYZP22RJS94xj7pN5qCXdTrF94asQ&#038;oe=6A0AA9F4\" alt=\"\ud83c\udfb6 Audici\u00f3n | Oboe Solista \ud83c\udfb6\n\nLa Brandenburgisches Staatsorchester Frankfurt convoca 1 plaza de Oboe Solista (100%), con contrato fijo.\n\n\ud83d\udccd Lugar: Messehalle, Frankfurt (Oder), Alemania\n\ud83d\udcc5 Audici\u00f3n: 23 de junio de 2026\n\u23f0 Fecha l\u00edmite de inscripci\u00f3n: 19 de mayo de 2026\n\n\ud83d\udd17 Bases y solicitud \ud83d\udc49 https:\/\/www.muvac.com\/es\/vacancy\/brandenburgisches-staatsorchester-frankfurt-oder-j16vrqv1\n\ud83d\udce3 Comparte con quien est\u00e9 preparando pruebas de orquesta.\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n--\n\n\ud83c\udfb6 Audition | Principal Oboe \ud83c\udfb6\n\nThe Brandenburgisches Staatsorchester Frankfurt is offering 1 Principal Oboe position (100%), with a permanent contract.\n\n\ud83d\udccd Location: Messehalle, Frankfurt (Oder), Germany\n\ud83d\udcc5 Audition date: June 23, 2026\n\u23f0 Application deadline: May 19, 2026\n\n\ud83d\udd17 Details and application \ud83d\udc49 https:\/\/www.muvac.com\/es\/vacancy\/brandenburgisches-staatsorchester-frankfurt-oder-j16vrqv1\n\ud83d\udce3 Share with anyone preparing orchestral auditions.\n\nBest wishes and good reeds! \ud83d\udc4b\ud83c\udfb6\n\n#Oboe #Auditions #Orchestra #Oboists #ClassicalMusic #OrchestralAuditions\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\ud83c\udfb6 Audici\u00f3n | Oboe Solista \ud83c\udfb6\n\nLa Brandenburgisches Staatsorchester Frankfurt convoca 1 plaza de Oboe Solista (100%), con contrato fijo.\n\n\ud83d\udccd Lugar: Messehalle, Frankfurt (Oder), Alemania\n\ud83d\udcc5 Audici\u00f3n: 23 de junio de 2026\n\u23f0 Fecha l\u00edmite de inscripci\u00f3n: 19 de mayo de 2026\n\n\ud83d\udd17 Bases y solicitud \ud83d\udc49 https:\/\/www.muvac.com\/es\/vacancy\/brandenburgisches-staatsorchester-frankfurt-oder-j16vrqv1\n\ud83d\udce3 Comparte con quien est\u00e9 preparando pruebas de orquesta.\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n--\n\n\ud83c\udfb6 Audition | Principal Oboe \ud83c\udfb6\n\nThe Brandenburgisches Staatsorchester Frankfurt is offering 1 Principal Oboe position (100%), with a permanent contract.\n\n\ud83d\udccd Location: Messehalle, Frankfurt (Oder), Germany\n\ud83d\udcc5 Audition date: June 23, 2026\n\u23f0 Application deadline: May 19, 2026\n\n\ud83d\udd17 Details and application \ud83d\udc49 https:\/\/www.muvac.com\/es\/vacancy\/brandenburgisches-staatsorchester-frankfurt-oder-j16vrqv1\n\ud83d\udce3 Share with anyone preparing orchestral auditions.\n\nBest wishes and good reeds! \ud83d\udc4b\ud83c\udfb6\n\n#Oboe #Auditions #Orchestra #Oboists #ClassicalMusic #OrchestralAuditions<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--video\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/reel\/DXMtM3WDKVa\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg4-3.cdninstagram.com\/v\/t51.82787-15\/671269162_18573705517010353_2013113010144177018_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=111&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=Fjk7JYfqh-cQ7kNvwEEMl7s&#038;_nc_oc=AdoKX6rDhVD7chJ42vBR6Pqz8qXkgc0AJ53zmI85daUjin3ygKOTpr0eZi23T_36eBivB8-rw2r7N1dqP_MmMpZk&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg4-3.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQHCaJ9NFmIvPyh0LiXfhY0dYEGNoK3nUgb6RCOSfLfz2bYvOIpkmiDS7RioyRhiwKM8OSB9XdIr&#038;oh=00_Af77FgDM8_OLO3fu32PwUhtJ9zlCMfuvCmUGV43c8rtidQ&#038;oe=6A0AB61E\" alt=\"\ud83e\uddd0 \u00bfProblemas de emisi\u00f3n?\n\nConstantemente veo obo\u00edstas que soplan m\u00e1s, aprietan m\u00e1s\u2026 y el sonido no mejora.\n\nEn este v\u00eddeo te ense\u00f1o c\u00f3mo trabajo esto con el simulador.\n\nSi quieres mejorar de verdad, tienes el simulador en EG-REEDS (link en comentarios).\n\nCuando lo pruebas\u2026 lo notas.\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n--\n\n\ud83e\uddd0 Emission problems?\n\nI constantly see oboists blowing more, squeezing more\u2026 and the sound doesn\u2019t improve.\n\nIn this video I show you how I work on this with the simulator.\n\nIf you really want to improve, you can get it at EG-REEDS (link in comments).\n\nOnce you try it\u2026 you feel the difference.\n\nBest wishes and good reeds! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboist #oboista #sound #sonido\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\ud83e\uddd0 \u00bfProblemas de emisi\u00f3n?\n\nConstantemente veo obo\u00edstas que soplan m\u00e1s, aprietan m\u00e1s\u2026 y el sonido no mejora.\n\nEn este v\u00eddeo te ense\u00f1o c\u00f3mo trabajo esto con el simulador.\n\nSi quieres mejorar de verdad, tienes el simulador en EG-REEDS (link en comentarios).\n\nCuando lo pruebas\u2026 lo notas.\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n--\n\n\ud83e\uddd0 Emission problems?\n\nI constantly see oboists blowing more, squeezing more\u2026 and the sound doesn\u2019t improve.\n\nIn this video I show you how I work on this with the simulator.\n\nIf you really want to improve, you can get it at EG-REEDS (link in comments).\n\nOnce you try it\u2026 you feel the difference.\n\nBest wishes and good reeds! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboist #oboista #sound #sonido<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--video\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/reel\/DXE-n0tCS3z\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg4-2.cdninstagram.com\/v\/t51.82787-15\/670326998_18573095485010353_22682814011938623_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=101&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=bkZMRL9EIYoQ7kNvwHWxcvT&#038;_nc_oc=Adrn5WfoXJXEdeXEJ20nHAgx5bZQml0dr87MVW-hUI0cLnTZeWVPuPCR8_pqtqbraZ6bXyhY7np9vZ1GK0kWJbzV&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg4-2.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQHP5hoCDoxPBKvkQxVKvJQtlX71dxqjtZbksIT8QHDnk9xb4cUZFW40MUA6hkpL1kY0wsyIAkw3&#038;oh=00_Af5HFWQ2t2tjmh5UYqxmKnaLrH8cUbxu_dBSJA8FKfdxOw&#038;oe=6A0AB989\" alt=\"\ud83c\udfa7 Nuevo episodio de La Comunidad del Oboe con Joaqu\u00edn Sanz\n\n\ud83d\udd25Ya tienes disponible el podcast con Joaqu\u00edn Sanz, obo\u00edsta solista en el Staatstheater Darmstadt @staatstheaterdarmstadt \n\nHa sido academista en la Staatsoper Hamburg, oboe solista en la EUYO y ha colaborado con orquestas como la hr-Sinfonieorchester Frankfurt y la Bamberger Symphoniker.\n\nHablamos sobre su camino hasta conseguir una plaza de solista, su experiencia en orquestas europeas, la realidad del d\u00eda a d\u00eda en una orquesta profesional y el Hermes Oboe Festival, del que es fundador.\n\n\ud83d\udc49 Ya lo puedes ver aqu\u00ed:\n\n\ud83c\udf0d www.lacomunidaddeloboe.com\n\n\ud83d\udcac Dale like, suscr\u00edbete y comp\u00e1rtelo con quien t\u00fa quieras\n\n\u00a1Saludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #podcast #orquesta #oboista #musicos #musicaclasica #orchestra\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\ud83c\udfa7 Nuevo episodio de La Comunidad del Oboe con Joaqu\u00edn Sanz\n\n\ud83d\udd25Ya tienes disponible el podcast con Joaqu\u00edn Sanz, obo\u00edsta solista en el Staatstheater Darmstadt @staatstheaterdarmstadt \n\nHa sido academista en la Staatsoper Hamburg, oboe solista en la EUYO y ha colaborado con orquestas como la hr-Sinfonieorchester Frankfurt y la Bamberger Symphoniker.\n\nHablamos sobre su camino hasta conseguir una plaza de solista, su experiencia en orquestas europeas, la realidad del d\u00eda a d\u00eda en una orquesta profesional y el Hermes Oboe Festival, del que es fundador.\n\n\ud83d\udc49 Ya lo puedes ver aqu\u00ed:\n\n\ud83c\udf0d www.lacomunidaddeloboe.com\n\n\ud83d\udcac Dale like, suscr\u00edbete y comp\u00e1rtelo con quien t\u00fa quieras\n\n\u00a1Saludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #podcast #orquesta #oboista #musicos #musicaclasica #orchestra<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--image\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/p\/DW_1Gv0iEJ_\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg4-2.cdninstagram.com\/v\/t39.30808-6\/669723010_1481633973974103_7331389148169638185_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=109&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&#038;_nc_ohc=UzVODqKZViwQ7kNvwEn-t6t&#038;_nc_oc=AdpjB0iuvjUYGfep7AwkE_z0gWTwVouAMsppCrGRRe9wmlW7vhQfdadwFw6ZgUk13gtqc3HPyEAlPrx6DaCMN0UX&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg4-2.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQHVhy-yEH-c-gS9MIk5QGcGwDljFEHFL30YQH0ZrKMEH6F3KOng4MhY9tCJl6pl3-7D6hrrtFKM&#038;oh=00_Af6lTWt2d4IwLX_XKLaiZ2K3quzEKO9wX-nVBmmV057uiA&#038;oe=6A0AACE4\" alt=\"\ud83c\udf99\ufe0f\u2728 Este lunes vuelve el podcast de La Comunidad del Oboe y nos acompa\u00f1a Joaqu\u00edn Sanz \ud83d\udc4f\u263a\ufe0f\n\nOboe solista en el Staatstheater Darmstadt @staatstheaterdarmstadt y fundador del Hermes Oboe Festival.\n\nHa sido academista en la Staatsoper Hamburg, oboe solista en la EUYO y ha colaborado con orquestas como la hr-Sinfonieorchester Frankfurt y la Bamberger Symphoniker.\n\n\ud83d\udd25 \u00a1No te lo pierdas! \ud83d\udd25\n\n\ud83d\udd17 www.lacomunidaddeloboe.com\n\n\u00a1Saludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboist #podcast #musica #orquesta\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\ud83c\udf99\ufe0f\u2728 Este lunes vuelve el podcast de La Comunidad del Oboe y nos acompa\u00f1a Joaqu\u00edn Sanz \ud83d\udc4f\u263a\ufe0f\n\nOboe solista en el Staatstheater Darmstadt @staatstheaterdarmstadt y fundador del Hermes Oboe Festival.\n\nHa sido academista en la Staatsoper Hamburg, oboe solista en la EUYO y ha colaborado con orquestas como la hr-Sinfonieorchester Frankfurt y la Bamberger Symphoniker.\n\n\ud83d\udd25 \u00a1No te lo pierdas! \ud83d\udd25\n\n\ud83d\udd17 www.lacomunidaddeloboe.com\n\n\u00a1Saludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboist #podcast #musica #orquesta<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--video\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/reel\/DW6qHlwiEAH\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg4-2.cdninstagram.com\/v\/t51.82787-15\/658952312_18572373499010353_1747444268410867699_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=109&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=dfI2N_ZcCJsQ7kNvwEpQrTR&#038;_nc_oc=AdpPOIFvLkhdXzh_IPpeDbrlYortGTl5YBhhrnq-mYbStzES2Sf_tBaWss2WrOdO0fdulwWDdaearFKg6EKWe_pC&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg4-2.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQGCkMGtBduck9L9DUMus6QnVHrWR5x4OpbDGjcQOAbQLi-ljN3WVuGbdYokgCmL8Vtx6MQiMlev&#038;oh=00_Af6ldahe5KLZIrXyZTiU7Tl30ujA-n5mDypDMhRCv6NqBQ&#038;oe=6A0AA9E3\" alt=\"Breaking news!! \ud83d\udea8 In addition to the Nutella, an oboe reed has snuck onto Artemis II, on its way to the Moon.\n\u2014\n\n\u00daltima hora!! \ud83d\udea8 Adem\u00e1s de la Nutella, se ha colado una ca\u00f1a de oboe en Artemis II, camino a la luna.\n\n#oboe #artemis #nasa #oboist #oboista #oboereed\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">Breaking news!! \ud83d\udea8 In addition to the Nutella, an oboe reed has snuck onto Artemis II, on its way to the Moon.\n\u2014\n\n\u00daltima hora!! \ud83d\udea8 Adem\u00e1s de la Nutella, se ha colado una ca\u00f1a de oboe en Artemis II, camino a la luna.\n\n#oboe #artemis #nasa #oboist #oboista #oboereed<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--video\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/reel\/DW1igOMiVdk\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg4-1.cdninstagram.com\/v\/t51.82787-15\/669532501_18571602991010353_7416216975769033423_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=108&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=FUYNdzerougQ7kNvwF6OBLP&#038;_nc_oc=Adqy_XccmgSTw4GJt_H4s1EtdeyL4Dgq_N2lxnm4nqgSI2KaHHcoHBmF7GW3uEZSt_KIYABPAtaSecMf8vc8p0Bh&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg4-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQHMBnRxtoM6zSb8T3qTcnw_s-8jrxLm6m5BTS2xkN3VbppODOpEYTwsB95ZwfePEKK38r2BtDni&#038;oh=00_Af4J5j8DtZ2KRPfr_ldb0bfQB6-Pt_8Ky4rQzd0oiMpvpw&#038;oe=6A0AB96D\" alt=\"\ud83c\udf99\ufe0f El lunes 13 volvemos con el podcast! Pero antes\u2026\n\nMira todo lo que te est\u00e1s perdiendo \ud83d\udc47\n\n\u00c1ngel Luis S\u00e1nchez\nMiriam Pastor\nRafael Cu\u00e9llar\nV\u00edctor Manuel \u00c1nchel\nGuillermo Sanchis\nLourdes Higes\nJuan Carlos Rivas\nIria Folgado y muchos m\u00e1s.\n\n\ud83d\udc49 Entra en www.lacomunidaddeloboe.com\n y puedes ver ya todas las entrevistas completas.\n\nSi tocas el oboe\u2026 esto es para ti \u263a\ufe0f\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\ud83c\udf99\ufe0f El lunes 13 volvemos con el podcast! Pero antes\u2026\n\nMira todo lo que te est\u00e1s perdiendo \ud83d\udc47\n\n\u00c1ngel Luis S\u00e1nchez\nMiriam Pastor\nRafael Cu\u00e9llar\nV\u00edctor Manuel \u00c1nchel\nGuillermo Sanchis\nLourdes Higes\nJuan Carlos Rivas\nIria Folgado y muchos m\u00e1s.\n\n\ud83d\udc49 Entra en www.lacomunidaddeloboe.com\n y puedes ver ya todas las entrevistas completas.\n\nSi tocas el oboe\u2026 esto es para ti \u263a\ufe0f\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--video\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/reel\/DWPAxRkDfzI\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg6-1.cdninstagram.com\/v\/t51.82787-15\/656422465_18568294918010353_716591356323613862_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=103&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=YJfPQIRfn1cQ7kNvwEKj6Tx&#038;_nc_oc=AdqS6LX2XZijkNCrI4v35KO7osguJWES4X9bvr99IM7PF_dHtmA6IqOBkPastUJW31lPaEsrXjkDfOTOue_dSD9z&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg6-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQGwwJVikNG-KYEPVE7Rmjr5e61y0etSbPzNrRgxEJ4G7lCWxLSPUs8RmAGwwBlpMTGzTgBwc_-f&#038;oh=00_Af6KHYjtK28RArMOJuVJrNPp_mpHRN0glLua-xAIyPdwXw&#038;oe=6A0AAF7D\" alt=\"\ud83c\udfa7 Nuevo episodio de La Comunidad del Oboe con Raquel Alves.\n\n\ud83d\udd25Ya tienes disponible el podcast con Raquel Alves, obo\u00edsta solista en la Henryk Wieniawski Philharmonic de Lublin (Filharmonia Lubelska) @filharmonialubelska \n\nHa formado parte de orquestas como la World Youth Orchestra o la Joven de la Sinf\u00f3nica de Galicia, y colaborado con Filarm\u00f3nica Nacional de Varsovia o la Orquesta de Extremadura.\n\nHablamos sobre su experiencia en orquestas internacionales, el camino hacia una plaza de solista y la exigencia del d\u00eda a d\u00eda en una orquesta profesional.\n\n\ud83d\udc49 Ya lo puedes ver aqu\u00ed:\n\n\ud83c\udf0d www.lacomunidaddeloboe.com\n\n\ud83d\udcac Dale like, suscr\u00edbete y comp\u00e1rtelo con quien t\u00fa quieras.\n\n\u00a1Saludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #podcast #orquesta #oboista #musicos #musicaclasica #orchestra\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">\ud83c\udfa7 Nuevo episodio de La Comunidad del Oboe con Raquel Alves.\n\n\ud83d\udd25Ya tienes disponible el podcast con Raquel Alves, obo\u00edsta solista en la Henryk Wieniawski Philharmonic de Lublin (Filharmonia Lubelska) @filharmonialubelska \n\nHa formado parte de orquestas como la World Youth Orchestra o la Joven de la Sinf\u00f3nica de Galicia, y colaborado con Filarm\u00f3nica Nacional de Varsovia o la Orquesta de Extremadura.\n\nHablamos sobre su experiencia en orquestas internacionales, el camino hacia una plaza de solista y la exigencia del d\u00eda a d\u00eda en una orquesta profesional.\n\n\ud83d\udc49 Ya lo puedes ver aqu\u00ed:\n\n\ud83c\udf0d www.lacomunidaddeloboe.com\n\n\ud83d\udcac Dale like, suscr\u00edbete y comp\u00e1rtelo con quien t\u00fa quieras.\n\n\u00a1Saludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #podcast #orquesta #oboista #musicos #musicaclasica #orchestra<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--image\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/p\/DWJ3eaPjB-q\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg6-1.cdninstagram.com\/v\/t51.82787-15\/655281022_18567013555010353_100021051030876352_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=103&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiRkVFRC5iZXN0X2ltYWdlX3VybGdlbi5DMyJ9&#038;_nc_ohc=wnGSBBVzb0AQ7kNvwGMgDbD&#038;_nc_oc=AdowRlZIr9widcAtPCgrJauCdSIUOOIloeSBz1RpXCYo7m7bpV74KiCtDyyNl4w3a_g7nv1ASticjXxEupnSjrWY&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg6-1.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQEL2cVEGNFROhsJfTGoHhlwpWuOTwYKLksPcbniQZT7hEEayulHUqx-0YzUHlBmpIRhQ6sGNE4S&#038;oh=00_Af5GqTSkrPdLiqfqzlhW7wxdkawLZX4P4xsFt7yqX8tbPw&#038;oe=6A0A8EAA\" alt=\"Este lunes 23 a las 18:00h tienes nuevo podcast en La Comunidad del Oboe \ud83c\udf99\ufe0f\u2728 Nos acompa\u00f1a Raquel Alves \ud83d\udc4f\u263a\ufe0f\n\nDesde 2023, es oboe solista en la Henryk Wieniawski Philharmonic de Lublin (Filharmonia Lubelska) @filharmonialubelska\n\nAdem\u00e1s, ha formado parte de orquestas como la World Youth Orchestra o la Joven de la Sinf\u00f3nica de Galicia, y ha colaborado con agrupaciones como la Filarm\u00f3nica Nacional de Varsovia o la Orquesta de Extremadura.\n\n\ud83d\udd25 \u00a1No te lo pierdas! \ud83d\udd25\n\n\ud83d\udd17 Tienes todos los episodios en: www.lacomunidaddeloboe.com\n\n\u00a1Saludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboist #podcast #musica\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">Este lunes 23 a las 18:00h tienes nuevo podcast en La Comunidad del Oboe \ud83c\udf99\ufe0f\u2728 Nos acompa\u00f1a Raquel Alves \ud83d\udc4f\u263a\ufe0f\n\nDesde 2023, es oboe solista en la Henryk Wieniawski Philharmonic de Lublin (Filharmonia Lubelska) @filharmonialubelska\n\nAdem\u00e1s, ha formado parte de orquestas como la World Youth Orchestra o la Joven de la Sinf\u00f3nica de Galicia, y ha colaborado con agrupaciones como la Filarm\u00f3nica Nacional de Varsovia o la Orquesta de Extremadura.\n\n\ud83d\udd25 \u00a1No te lo pierdas! \ud83d\udd25\n\n\ud83d\udd17 Tienes todos los episodios en: www.lacomunidaddeloboe.com\n\n\u00a1Saludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n\n#oboe #oboist #podcast #musica<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><div class=\"col\" ><div class=\"col-inner\"><div class=\"img has-hover no-overflow\">\n\t\t\t\t\t<div class=\"dark instagram-image-container image-overlay-remove instagram-image-type--video\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/reel\/DWHb6JfD1HT\/\" target=\"_blank\" rel=\"noopener\" class=\"plain\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/scontent-cdg4-2.cdninstagram.com\/v\/t51.82787-15\/654650321_18567065839010353_102183869284756658_n.jpg?stp=dst-jpg_e35_tt6&#038;_nc_cat=107&#038;ccb=7-5&#038;_nc_sid=18de74&#038;efg=eyJlZmdfdGFnIjoiQ0xJUFMuYmVzdF9pbWFnZV91cmxnZW4uQzMifQ%3D%3D&#038;_nc_ohc=KEa1F5ooTp0Q7kNvwG4CClb&#038;_nc_oc=AdpT3t5rJTZpm_qE8T0Z1BDkDia038OBSoPvrFAkhkksJX6gn3NjukRy1ZDDy2QI4RtMveMJ9bo8ov7ttH8Snm12&#038;_nc_zt=23&#038;_nc_ht=scontent-cdg4-2.cdninstagram.com&#038;edm=ANo9K5cEAAAA&#038;_nc_gid=qTP5B8RTna4-UKLu7o3nVg&#038;_nc_tpa=Q5bMBQE4qu5h1oSCtLSq-t3BInVI-i8gedlNNSbQiGVv5t4Aw7aVhECe8XdYwAuSSUkTjWyFZDTQReaB&#038;oh=00_Af7ok_7Hx1vE3-jbL2M2UGFovGmYE2kmepIx41dyHouHxw&#038;oe=6A0AB6B1\" alt=\"Hay cosas que no necesitan mucha explicaci\u00f3n. Las ves, encajan contigo y van directas tu carrito.\n\n\u00bfCu\u00e1l no dejar\u00edas pasar?\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n----\nSome things do not need much explanation. You see them, they fit you, and they go straight into the cart.\n\nWhich one would you not let pass?\n\nBest wishes and good reeds! \ud83d\udc4b\ud83c\udfb6\n\n\ud83d\udcbb www.eg-reeds.com\n\u2709\ufe0f info@eg-reeds.com\n\ud83d\udcde +34 676628251\n\n#egreeds  #Oboe #OboeReeds #Ca\u00f1asDeOboe #ReedMaking #Oboist\"\/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"caption\">Hay cosas que no necesitan mucha explicaci\u00f3n. Las ves, encajan contigo y van directas tu carrito.\n\n\u00bfCu\u00e1l no dejar\u00edas pasar?\n\nSaludos y buenas ca\u00f1as! \ud83d\udc4b\ud83c\udfb6\n----\nSome things do not need much explanation. You see them, they fit you, and they go straight into the cart.\n\nWhich one would you not let pass?\n\nBest wishes and good reeds! \ud83d\udc4b\ud83c\udfb6\n\n\ud83d\udcbb www.eg-reeds.com\n\u2709\ufe0f info@eg-reeds.com\n\ud83d\udcde +34 676628251\n\n#egreeds  #Oboe #OboeReeds #Ca\u00f1asDeOboe #ReedMaking #Oboist<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div><\/div><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00edguenos en Instagram @egreeds S\u00edguenos en Instagram para estar al d\u00eda de todas las novedades. Nuestro usuario es @egreeds . Tambi\u00e9n puedes seguirnos en todas nuestras redes sociales solo tienes que hacer clic en los iconos de abajo. Recuerda que nuestra tienda online de ca\u00f1as y palas de oboe y todo lo necesario para su [&#8230;]\n","protected":false},"author":1,"featured_media":46318,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1934],"tags":[],"class_list":["post-46317","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eg-reeds-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>S\u00edguenos en Instagram @egreeds - www.eg-reeds.com<\/title>\n<meta name=\"description\" content=\"S\u00edguenos en Instagram para estar al d\u00eda de todas las novedades. Nuestro usuario es @egreeds . Tambi\u00e9n puedes seguirnos en otras redes sociales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00edguenos en Instagram @egreeds\" \/>\n<meta property=\"og:description\" content=\"S\u00edguenos en Instagram para estar al d\u00eda de todas las novedades. Nuestro usuario es @egreeds . Tambi\u00e9n puedes seguirnos en otras redes sociales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/\" \/>\n<meta property=\"og:site_name\" content=\"www.eg-reeds.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EGREEDS\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-01T11:18:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-22T11:21:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eg-reeds.com\/wp-content\/uploads\/2022\/06\/Oboe-reed-shavings-EG-REEDS.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u00c9ric Gonz\u00e1lez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@egreeds\" \/>\n<meta name=\"twitter:site\" content=\"@egreeds\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u00c9ric Gonz\u00e1lez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/\"},\"author\":{\"name\":\"\u00c9ric Gonz\u00e1lez\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/#\\\/schema\\\/person\\\/dba1f0630a37fc591e447a789cdbfe2b\"},\"headline\":\"S\u00edguenos en Instagram @egreeds\",\"datePublished\":\"2022-06-01T11:18:42+00:00\",\"dateModified\":\"2024-10-22T11:21:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/\"},\"wordCount\":98,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Oboe-reed-shavings-EG-REEDS.jpeg\",\"articleSection\":[\"EG-REEDS\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/\",\"name\":\"S\u00edguenos en Instagram @egreeds - www.eg-reeds.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Oboe-reed-shavings-EG-REEDS.jpeg\",\"datePublished\":\"2022-06-01T11:18:42+00:00\",\"dateModified\":\"2024-10-22T11:21:40+00:00\",\"description\":\"S\u00edguenos en Instagram para estar al d\u00eda de todas las novedades. Nuestro usuario es @egreeds . Tambi\u00e9n puedes seguirnos en otras redes sociales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Oboe-reed-shavings-EG-REEDS.jpeg\",\"contentUrl\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Oboe-reed-shavings-EG-REEDS.jpeg\",\"width\":1500,\"height\":500,\"caption\":\"Virutas ca\u00f1a oboe\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/siguenos-instagram-egreeds\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/tienda\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00edguenos en Instagram @egreeds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/\",\"name\":\"www.eg-reeds.com\",\"description\":\"Ca\u00f1as oboe\",\"publisher\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/#organization\"},\"alternateName\":\"eg-reeds.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/#organization\",\"name\":\"www.eg-reeds.com\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-scaled-e1718793906611.jpg\",\"contentUrl\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-scaled-e1718793906611.jpg\",\"width\":1200,\"height\":493,\"caption\":\"www.eg-reeds.com\"},\"image\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EGREEDS\",\"https:\\\/\\\/x.com\\\/egreeds\",\"https:\\\/\\\/www.instagram.com\\\/egreeds\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/EGREEDS\",\"https:\\\/\\\/www.threads.net\\\/@egreeds\",\"https:\\\/\\\/www.tiktok.com\\\/@egreeds\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/#\\\/schema\\\/person\\\/dba1f0630a37fc591e447a789cdbfe2b\",\"name\":\"\u00c9ric Gonz\u00e1lez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4cb32ced7ebea7949fa6b0ce026e8669193e020e041d77ac4507307974445a4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4cb32ced7ebea7949fa6b0ce026e8669193e020e041d77ac4507307974445a4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4cb32ced7ebea7949fa6b0ce026e8669193e020e041d77ac4507307974445a4?s=96&d=mm&r=g\",\"caption\":\"\u00c9ric Gonz\u00e1lez\"},\"url\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/author\\\/eric-gonzalez-oboe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"S\u00edguenos en Instagram @egreeds - www.eg-reeds.com","description":"S\u00edguenos en Instagram para estar al d\u00eda de todas las novedades. Nuestro usuario es @egreeds . Tambi\u00e9n puedes seguirnos en otras redes sociales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/","og_locale":"es_ES","og_type":"article","og_title":"S\u00edguenos en Instagram @egreeds","og_description":"S\u00edguenos en Instagram para estar al d\u00eda de todas las novedades. Nuestro usuario es @egreeds . Tambi\u00e9n puedes seguirnos en otras redes sociales.","og_url":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/","og_site_name":"www.eg-reeds.com","article_publisher":"https:\/\/www.facebook.com\/EGREEDS","article_published_time":"2022-06-01T11:18:42+00:00","article_modified_time":"2024-10-22T11:21:40+00:00","og_image":[{"width":1500,"height":500,"url":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2022\/06\/Oboe-reed-shavings-EG-REEDS.jpeg","type":"image\/jpeg"}],"author":"\u00c9ric Gonz\u00e1lez","twitter_card":"summary_large_image","twitter_creator":"@egreeds","twitter_site":"@egreeds","twitter_misc":{"Escrito por":"\u00c9ric Gonz\u00e1lez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/#article","isPartOf":{"@id":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/"},"author":{"name":"\u00c9ric Gonz\u00e1lez","@id":"https:\/\/eg-reeds.com\/es\/#\/schema\/person\/dba1f0630a37fc591e447a789cdbfe2b"},"headline":"S\u00edguenos en Instagram @egreeds","datePublished":"2022-06-01T11:18:42+00:00","dateModified":"2024-10-22T11:21:40+00:00","mainEntityOfPage":{"@id":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/"},"wordCount":98,"commentCount":0,"publisher":{"@id":"https:\/\/eg-reeds.com\/es\/#organization"},"image":{"@id":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/#primaryimage"},"thumbnailUrl":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2022\/06\/Oboe-reed-shavings-EG-REEDS.jpeg","articleSection":["EG-REEDS"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/","url":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/","name":"S\u00edguenos en Instagram @egreeds - www.eg-reeds.com","isPartOf":{"@id":"https:\/\/eg-reeds.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/#primaryimage"},"image":{"@id":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/#primaryimage"},"thumbnailUrl":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2022\/06\/Oboe-reed-shavings-EG-REEDS.jpeg","datePublished":"2022-06-01T11:18:42+00:00","dateModified":"2024-10-22T11:21:40+00:00","description":"S\u00edguenos en Instagram para estar al d\u00eda de todas las novedades. Nuestro usuario es @egreeds . Tambi\u00e9n puedes seguirnos en otras redes sociales.","breadcrumb":{"@id":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/#primaryimage","url":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2022\/06\/Oboe-reed-shavings-EG-REEDS.jpeg","contentUrl":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2022\/06\/Oboe-reed-shavings-EG-REEDS.jpeg","width":1500,"height":500,"caption":"Virutas ca\u00f1a oboe"},{"@type":"BreadcrumbList","@id":"https:\/\/eg-reeds.com\/es\/siguenos-instagram-egreeds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/eg-reeds.com\/es\/tienda\/"},{"@type":"ListItem","position":2,"name":"S\u00edguenos en Instagram @egreeds"}]},{"@type":"WebSite","@id":"https:\/\/eg-reeds.com\/es\/#website","url":"https:\/\/eg-reeds.com\/es\/","name":"www.eg-reeds.com","description":"Ca\u00f1as oboe","publisher":{"@id":"https:\/\/eg-reeds.com\/es\/#organization"},"alternateName":"eg-reeds.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eg-reeds.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eg-reeds.com\/es\/#organization","name":"www.eg-reeds.com","url":"https:\/\/eg-reeds.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eg-reeds.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2024\/06\/Logo-scaled-e1718793906611.jpg","contentUrl":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2024\/06\/Logo-scaled-e1718793906611.jpg","width":1200,"height":493,"caption":"www.eg-reeds.com"},"image":{"@id":"https:\/\/eg-reeds.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EGREEDS","https:\/\/x.com\/egreeds","https:\/\/www.instagram.com\/egreeds\/","https:\/\/www.youtube.com\/c\/EGREEDS","https:\/\/www.threads.net\/@egreeds","https:\/\/www.tiktok.com\/@egreeds"]},{"@type":"Person","@id":"https:\/\/eg-reeds.com\/es\/#\/schema\/person\/dba1f0630a37fc591e447a789cdbfe2b","name":"\u00c9ric Gonz\u00e1lez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f4cb32ced7ebea7949fa6b0ce026e8669193e020e041d77ac4507307974445a4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4cb32ced7ebea7949fa6b0ce026e8669193e020e041d77ac4507307974445a4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4cb32ced7ebea7949fa6b0ce026e8669193e020e041d77ac4507307974445a4?s=96&d=mm&r=g","caption":"\u00c9ric Gonz\u00e1lez"},"url":"https:\/\/eg-reeds.com\/es\/author\/eric-gonzalez-oboe\/"}]}},"_links":{"self":[{"href":"https:\/\/eg-reeds.com\/es\/wp-json\/wp\/v2\/posts\/46317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eg-reeds.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eg-reeds.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eg-reeds.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eg-reeds.com\/es\/wp-json\/wp\/v2\/comments?post=46317"}],"version-history":[{"count":0,"href":"https:\/\/eg-reeds.com\/es\/wp-json\/wp\/v2\/posts\/46317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eg-reeds.com\/es\/wp-json\/wp\/v2\/media\/46318"}],"wp:attachment":[{"href":"https:\/\/eg-reeds.com\/es\/wp-json\/wp\/v2\/media?parent=46317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eg-reeds.com\/es\/wp-json\/wp\/v2\/categories?post=46317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eg-reeds.com\/es\/wp-json\/wp\/v2\/tags?post=46317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}