{"id":13298,"date":"2015-09-16T12:51:41","date_gmt":"2015-09-16T10:51:41","guid":{"rendered":""},"modified":"2017-01-17T18:32:17","modified_gmt":"2017-01-17T18:32:17","slug":"fil-pour-anches-vert","status":"publish","type":"product","link":"https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/","title":{"rendered":"Fil pour anches vert"},"content":{"rendered":"<p><strong>Fil pour anches vert.<\/strong><\/p>\n<p>100% nylon avec un diam\u00e8tre de 0,30 millim\u00e8tres. 250\u00a0m\u00e8tres de longueur. Disponible dans un assortiment de couleurs \u00e0 choisir.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fil pour anches vert. 100% nylon avec un diam\u00e8tre de 0,30 millim\u00e8tres. 250\u00a0m\u00e8tres de longueur. Disponible dans un assortiment de couleurs \u00e0 choisir.<\/p>\n","protected":false},"featured_media":24058,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1415,421],"product_tag":[],"giftcard-category":[],"class_list":["post-13298","product","type-product","status-publish","has-post-thumbnail","product_cat-accessoires","product_cat-fils","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fil pour anches vert | EG-REEDS<\/title>\n<meta name=\"description\" content=\"Fil pour anches vert, fil, anches, hautbois\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fil pour anches vert\" \/>\n<meta property=\"og:description\" content=\"Fil pour anches vert, fil, anches, hautbois\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/\" \/>\n<meta property=\"og:site_name\" content=\"EG-REEDS\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EGREEDS\" \/>\n<meta property=\"article:modified_time\" content=\"2017-01-17T18:32:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eg-reeds.com\/wp-content\/uploads\/2017\/01\/Green-thread-for-reeds.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"544\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@egreeds\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"10,90&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/shop\\\/accessoires\\\/fils\\\/fil-pour-anches-vert\\\/\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/shop\\\/accessoires\\\/fils\\\/fil-pour-anches-vert\\\/\",\"name\":\"Fil pour anches vert | EG-REEDS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/shop\\\/accessoires\\\/fils\\\/fil-pour-anches-vert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/shop\\\/accessoires\\\/fils\\\/fil-pour-anches-vert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Green-thread-for-reeds.jpg\",\"datePublished\":\"2015-09-16T10:51:41+00:00\",\"dateModified\":\"2017-01-17T18:32:17+00:00\",\"description\":\"Fil pour anches vert, fil, anches, hautbois\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/shop\\\/accessoires\\\/fils\\\/fil-pour-anches-vert\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/shop\\\/accessoires\\\/fils\\\/fil-pour-anches-vert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/shop\\\/accessoires\\\/fils\\\/fil-pour-anches-vert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Green-thread-for-reeds.jpg\",\"contentUrl\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2017\\\/01\\\/Green-thread-for-reeds.jpg\",\"width\":640,\"height\":544},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/shop\\\/accessoires\\\/fils\\\/fil-pour-anches-vert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fil pour anches vert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/\",\"name\":\"EG-REEDS\",\"description\":\"Anches hautbois\",\"publisher\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/#organization\"},\"alternateName\":\"EG REEDS\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/#organization\",\"name\":\"EG-REEDS\",\"alternateName\":\"EG REEDS\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-EG-REEDS-scaled.png\",\"contentUrl\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-EG-REEDS-scaled.png\",\"width\":2886,\"height\":1083,\"caption\":\"EG-REEDS\"},\"image\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EGREEDS\",\"https:\\\/\\\/x.com\\\/egreeds\",\"https:\\\/\\\/www.instagram.com\\\/egreeds\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/EGREEDS\",\"https:\\\/\\\/www.threads.net\\\/@egreeds\",\"https:\\\/\\\/www.tiktok.com\\\/@egreeds\"],\"description\":\"EG-REEDS est une entreprise en ligne sp\u00e9cialis\u00e9e dans les anches de hautbois, les hautbois, la location de hautbois, les accessoires et le mat\u00e9riel pour hautbo\u00efstes. Bas\u00e9e \u00e0 Ponferrada, Le\u00f3n, Espagne, nous vendons dans le monde entier et aidons les \u00e9tudiants en hautbois, les hautbo\u00efstes professionnels, les enseignants et les familles \u00e0 trouver des anches de hautbois fiables et des solutions pour jouer avec plus de confiance. Avec plus de 10 ans d'exp\u00e9rience, EG-REEDS combine la fabrication d'anches en interne, l'expertise professionnelle du hautbois, les ventes en ligne internationales et une communaut\u00e9 \u00e9ducative construite autour de l'instrument.\",\"email\":\"info@eg-reeds.com\",\"telephone\":\"676628251\",\"legalName\":\"EG-REEDS,CB\",\"foundingDate\":\"2015-01-01\",\"vatID\":\"ESE24707143\",\"ownershipFundingInfo\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/sobre-nosotros-eg-reeds\\\/\",\"actionableFeedbackPolicy\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/politica-de-privacidad\\\/\",\"correctionsPolicy\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/terminos-y-condiciones\\\/\",\"hasMerchantReturnPolicy\":{\"@type\":\"MerchantReturnPolicy\",\"merchantReturnLink\":\"https:\\\/\\\/eg-reeds.com\\\/es\\\/reembolso_devoluciones\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"10.90\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"ACHV\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fil pour anches vert | EG-REEDS","description":"Fil pour anches vert, fil, anches, hautbois","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/","og_locale":"fr_FR","og_type":"article","og_title":"Fil pour anches vert","og_description":"Fil pour anches vert, fil, anches, hautbois","og_url":"https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/","og_site_name":"EG-REEDS","article_publisher":"https:\/\/www.facebook.com\/EGREEDS","article_modified_time":"2017-01-17T18:32:17+00:00","og_image":[{"width":640,"height":544,"url":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2017\/01\/Green-thread-for-reeds.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@egreeds","twitter_misc":{"Prix":"10,90&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/","url":"https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/","name":"Fil pour anches vert | EG-REEDS","isPartOf":{"@id":"https:\/\/eg-reeds.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/#primaryimage"},"image":{"@id":"https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/#primaryimage"},"thumbnailUrl":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2017\/01\/Green-thread-for-reeds.jpg","datePublished":"2015-09-16T10:51:41+00:00","dateModified":"2017-01-17T18:32:17+00:00","description":"Fil pour anches vert, fil, anches, hautbois","breadcrumb":{"@id":"https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/#primaryimage","url":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2017\/01\/Green-thread-for-reeds.jpg","contentUrl":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2017\/01\/Green-thread-for-reeds.jpg","width":640,"height":544},{"@type":"BreadcrumbList","@id":"https:\/\/eg-reeds.com\/fr\/shop\/accessoires\/fils\/fil-pour-anches-vert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/eg-reeds.com\/fr\/boutique\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/eg-reeds.com\/fr\/boutique\/"},{"@type":"ListItem","position":3,"name":"Fil pour anches vert"}]},{"@type":"WebSite","@id":"https:\/\/eg-reeds.com\/fr\/#website","url":"https:\/\/eg-reeds.com\/fr\/","name":"EG-REEDS","description":"Anches hautbois","publisher":{"@id":"https:\/\/eg-reeds.com\/fr\/#organization"},"alternateName":"EG REEDS","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eg-reeds.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/eg-reeds.com\/fr\/#organization","name":"EG-REEDS","alternateName":"EG REEDS","url":"https:\/\/eg-reeds.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/eg-reeds.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2024\/06\/Logo-EG-REEDS-scaled.png","contentUrl":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2024\/06\/Logo-EG-REEDS-scaled.png","width":2886,"height":1083,"caption":"EG-REEDS"},"image":{"@id":"https:\/\/eg-reeds.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EGREEDS","https:\/\/x.com\/egreeds","https:\/\/www.instagram.com\/egreeds\/","https:\/\/www.youtube.com\/c\/EGREEDS","https:\/\/www.threads.net\/@egreeds","https:\/\/www.tiktok.com\/@egreeds"],"description":"EG-REEDS est une entreprise en ligne sp\u00e9cialis\u00e9e dans les anches de hautbois, les hautbois, la location de hautbois, les accessoires et le mat\u00e9riel pour hautbo\u00efstes. Bas\u00e9e \u00e0 Ponferrada, Le\u00f3n, Espagne, nous vendons dans le monde entier et aidons les \u00e9tudiants en hautbois, les hautbo\u00efstes professionnels, les enseignants et les familles \u00e0 trouver des anches de hautbois fiables et des solutions pour jouer avec plus de confiance. Avec plus de 10 ans d'exp\u00e9rience, EG-REEDS combine la fabrication d'anches en interne, l'expertise professionnelle du hautbois, les ventes en ligne internationales et une communaut\u00e9 \u00e9ducative construite autour de l'instrument.","email":"info@eg-reeds.com","telephone":"676628251","legalName":"EG-REEDS,CB","foundingDate":"2015-01-01","vatID":"ESE24707143","ownershipFundingInfo":"https:\/\/eg-reeds.com\/es\/sobre-nosotros-eg-reeds\/","actionableFeedbackPolicy":"https:\/\/eg-reeds.com\/es\/politica-de-privacidad\/","correctionsPolicy":"https:\/\/eg-reeds.com\/es\/terminos-y-condiciones\/","hasMerchantReturnPolicy":{"@type":"MerchantReturnPolicy","merchantReturnLink":"https:\/\/eg-reeds.com\/es\/reembolso_devoluciones\/"}}]},"product_price_amount":"10.90","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"ACHV","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/eg-reeds.com\/fr\/wp-json\/wp\/v2\/product\/13298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eg-reeds.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/eg-reeds.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/eg-reeds.com\/fr\/wp-json\/wp\/v2\/comments?post=13298"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eg-reeds.com\/fr\/wp-json\/wp\/v2\/media\/24058"}],"wp:attachment":[{"href":"https:\/\/eg-reeds.com\/fr\/wp-json\/wp\/v2\/media?parent=13298"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/eg-reeds.com\/fr\/wp-json\/wp\/v2\/product_brand?post=13298"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/eg-reeds.com\/fr\/wp-json\/wp\/v2\/product_cat?post=13298"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/eg-reeds.com\/fr\/wp-json\/wp\/v2\/product_tag?post=13298"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/eg-reeds.com\/fr\/wp-json\/wp\/v2\/giftcard-category?post=13298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}