{"id":8602,"count":1,"description":"","link":"https:\/\/eg-reeds.com\/ko\/\uce74\ud14c\uace0\ub9ac\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\/","name":"\uc624\ubcf4\uc5d0 \ub9ac\ub4dc","slug":"%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.0 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\uc624\ubcf4\uc5d0 \ub9ac\ub4dc - \uc624\ubcf4\uc5d0 |EG-REEDS<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eg-reeds.com\/ko\/\uce74\ud14c\uace0\ub9ac\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\/\" \/>\n<meta property=\"og:locale\" content=\"ko_KR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\uc624\ubcf4\uc5d0 \ub9ac\ub4dc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eg-reeds.com\/ko\/\uce74\ud14c\uace0\ub9ac\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\/\" \/>\n<meta property=\"og:site_name\" content=\"\uc624\ubcf4\uc5d0 |EG-REEDS\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eg-reeds.com\/wp-content\/uploads\/2018\/11\/EG-REEDS-Oboe-reeds-shop-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1010\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@egreeds\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/\uce74\ud14c\uace0\ub9ac\\\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\\\/\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/\uce74\ud14c\uace0\ub9ac\\\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\\\/\",\"name\":\"\uc624\ubcf4\uc5d0 \ub9ac\ub4dc - \uc624\ubcf4\uc5d0 |EG-REEDS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/\uce74\ud14c\uace0\ub9ac\\\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\\\/#breadcrumb\"},\"inLanguage\":\"ko-KR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/\uce74\ud14c\uace0\ub9ac\\\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\ud648\",\"item\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/%ec%83%81%ec%a0%90\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\uc624\ubcf4\uc5d0 \ub9ac\ub4dc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/#website\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/\",\"name\":\"www.eg-reeds.com\",\"description\":\"\uc624\ubcf4\uc5d0 \ub9ac\ub4dc\",\"publisher\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/#organization\"},\"alternateName\":\"eg-reeds.com\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ko-KR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/#organization\",\"name\":\"www.eg-reeds.com\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ko-KR\",\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-scaled-e1718793906611.jpg\",\"contentUrl\":\"https:\\\/\\\/eg-reeds.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Logo-scaled-e1718793906611.jpg\",\"width\":1200,\"height\":493,\"caption\":\"www.eg-reeds.com\"},\"image\":{\"@id\":\"https:\\\/\\\/eg-reeds.com\\\/ko\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EGREEDS\",\"https:\\\/\\\/x.com\\\/egreeds\",\"https:\\\/\\\/www.instagram.com\\\/egreeds\\\/\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/EGREEDS\",\"https:\\\/\\\/www.threads.net\\\/@egreeds\",\"https:\\\/\\\/www.tiktok.com\\\/@egreeds\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\uc624\ubcf4\uc5d0 \ub9ac\ub4dc - \uc624\ubcf4\uc5d0 |EG-REEDS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eg-reeds.com\/ko\/\uce74\ud14c\uace0\ub9ac\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\/","og_locale":"ko_KR","og_type":"article","og_title":"\uc624\ubcf4\uc5d0 \ub9ac\ub4dc","og_url":"https:\/\/eg-reeds.com\/ko\/\uce74\ud14c\uace0\ub9ac\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\/","og_site_name":"\uc624\ubcf4\uc5d0 |EG-REEDS","og_image":[{"width":2560,"height":1010,"url":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2018\/11\/EG-REEDS-Oboe-reeds-shop-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@egreeds","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/eg-reeds.com\/ko\/\uce74\ud14c\uace0\ub9ac\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\/","url":"https:\/\/eg-reeds.com\/ko\/\uce74\ud14c\uace0\ub9ac\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\/","name":"\uc624\ubcf4\uc5d0 \ub9ac\ub4dc - \uc624\ubcf4\uc5d0 |EG-REEDS","isPartOf":{"@id":"https:\/\/eg-reeds.com\/ko\/#website"},"breadcrumb":{"@id":"https:\/\/eg-reeds.com\/ko\/\uce74\ud14c\uace0\ub9ac\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\/#breadcrumb"},"inLanguage":"ko-KR"},{"@type":"BreadcrumbList","@id":"https:\/\/eg-reeds.com\/ko\/\uce74\ud14c\uace0\ub9ac\/%ec%98%a4%eb%b3%b4%ec%97%90-%eb%a6%ac%eb%93%9c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\ud648","item":"https:\/\/eg-reeds.com\/ko\/%ec%83%81%ec%a0%90\/"},{"@type":"ListItem","position":2,"name":"\uc624\ubcf4\uc5d0 \ub9ac\ub4dc"}]},{"@type":"WebSite","@id":"https:\/\/eg-reeds.com\/ko\/#website","url":"https:\/\/eg-reeds.com\/ko\/","name":"www.eg-reeds.com","description":"\uc624\ubcf4\uc5d0 \ub9ac\ub4dc","publisher":{"@id":"https:\/\/eg-reeds.com\/ko\/#organization"},"alternateName":"eg-reeds.com","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eg-reeds.com\/ko\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ko-KR"},{"@type":"Organization","@id":"https:\/\/eg-reeds.com\/ko\/#organization","name":"www.eg-reeds.com","url":"https:\/\/eg-reeds.com\/ko\/","logo":{"@type":"ImageObject","inLanguage":"ko-KR","@id":"https:\/\/eg-reeds.com\/ko\/#\/schema\/logo\/image\/","url":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2024\/06\/Logo-scaled-e1718793906611.jpg","contentUrl":"https:\/\/eg-reeds.com\/wp-content\/uploads\/2024\/06\/Logo-scaled-e1718793906611.jpg","width":1200,"height":493,"caption":"www.eg-reeds.com"},"image":{"@id":"https:\/\/eg-reeds.com\/ko\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EGREEDS","https:\/\/x.com\/egreeds","https:\/\/www.instagram.com\/egreeds\/","https:\/\/www.youtube.com\/c\/EGREEDS","https:\/\/www.threads.net\/@egreeds","https:\/\/www.tiktok.com\/@egreeds"]}]}},"_links":{"self":[{"href":"https:\/\/eg-reeds.com\/ko\/wp-json\/wp\/v2\/categories\/8602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eg-reeds.com\/ko\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/eg-reeds.com\/ko\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/eg-reeds.com\/ko\/wp-json\/wp\/v2\/posts?categories=8602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}